{"id":882,"date":"2026-07-06T13:09:38","date_gmt":"2026-07-06T11:09:38","guid":{"rendered":"https:\/\/award-stories.comprix.com\/club-der-fantasie\/?page_id=882"},"modified":"2026-07-06T16:32:51","modified_gmt":"2026-07-06T14:32:51","slug":"interview-bohlender","status":"publish","type":"page","link":"https:\/\/award-stories.comprix.com\/club-der-fantasie\/interview-bohlender\/","title":{"rendered":"Interview-bohlender"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"882\" class=\"elementor elementor-882\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ab7c5e4 e-flex e-con-boxed e-con e-parent\" data-id=\"ab7c5e4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-896f34a elementor-invisible elementor-widget elementor-widget-image\" data-id=\"896f34a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"737\" src=\"https:\/\/award-stories.comprix.com\/club-der-fantasie\/wp-content\/uploads\/2026\/06\/hirn-final-1024x943.png\" class=\"attachment-large size-large wp-image-235\" alt=\"\" srcset=\"https:\/\/award-stories.comprix.com\/club-der-fantasie\/wp-content\/uploads\/2026\/06\/hirn-final-1024x943.png 1024w, https:\/\/award-stories.comprix.com\/club-der-fantasie\/wp-content\/uploads\/2026\/06\/hirn-final-300x276.png 300w, https:\/\/award-stories.comprix.com\/club-der-fantasie\/wp-content\/uploads\/2026\/06\/hirn-final-768x708.png 768w, https:\/\/award-stories.comprix.com\/club-der-fantasie\/wp-content\/uploads\/2026\/06\/hirn-final.png 1500w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cae2a8d e-flex e-con-boxed e-con e-parent\" data-id=\"cae2a8d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9e99e63 e-con-full e-flex e-con e-child\" data-id=\"9e99e63\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-897a759 elementor-widget elementor-widget-heading\" data-id=\"897a759\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u201eBer\u00fchrbar bleiben\u201c <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8dd8f6 elementor-widget elementor-widget-heading\" data-id=\"f8dd8f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Christoph Bohlender (MENSCH Kreativagentur) \u00fcber Healthcare-Kommunikation und gute Juryarbeit beim COMPRIX<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f4d0048 e-flex e-con-boxed e-con e-parent\" data-id=\"f4d0048\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-510bf21 e-con-full e-flex e-con e-child\" data-id=\"510bf21\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-666e927 elementor-widget elementor-widget-image\" data-id=\"666e927\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"360\" height=\"456\" src=\"https:\/\/award-stories.comprix.com\/club-der-fantasie\/wp-content\/uploads\/2026\/07\/Beirat_Bohlender-Christoph-MENSCH_360x456px.jpg\" class=\"attachment-large size-large wp-image-892\" alt=\"\" srcset=\"https:\/\/award-stories.comprix.com\/club-der-fantasie\/wp-content\/uploads\/2026\/07\/Beirat_Bohlender-Christoph-MENSCH_360x456px.jpg 360w, https:\/\/award-stories.comprix.com\/club-der-fantasie\/wp-content\/uploads\/2026\/07\/Beirat_Bohlender-Christoph-MENSCH_360x456px-237x300.jpg 237w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-96d56f6 e-con-full e-flex e-con e-child\" data-id=\"96d56f6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e68b7b8 elementor-widget elementor-widget-heading\" data-id=\"e68b7b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">COMPRIX: Christoph, du bist neues Mitglied im COMPRIX-Beirat. Was treibt dich an, dich einzubringen?<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41b77fe elementor-widget elementor-widget-text-editor\" data-id=\"41b77fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Christoph Bohlender: <\/strong>Der COMPRIX ist f\u00fcr mich das wichtigste Vehikel f\u00fcr kreative Healthcare-Kommunikation in Deutschland. Er kann eine B\u00fchne sein, die \u00fcber die Branche hinaus Wirkung entfaltet \u2013 mit einer Relevanz, die auch au\u00dferhalb sp\u00fcrbar wird. Wir haben hier Themen auf dem Tisch, die wirklich z\u00e4hlen: Leben, Tod, Gesundheit, W\u00fcrde. Das ist mehr als Kampagne, mehr als Marketing \u2013 das ist Verantwortung.<\/p><p>Mich reizt die Vorstellung, dass der COMPRIX f\u00fcr Kreative vielleicht noch mehr zu einem Ort wird, an dem man unbedingt dabei sein m\u00f6chte \u2013 aus \u00dcberzeugung und aus Lust auf gute Arbeiten. Wenn der Award diese Anziehungskraft entfaltet, auch was die Punktrelevanz in den gro\u00dfen Rankings angeht, profitieren wir alle: unsere Branche, die Kunden und vor allem die Qualit\u00e4t der Arbeiten selbst.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ee1759 elementor-widget elementor-widget-heading\" data-id=\"8ee1759\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Hast Du konkrete Vorstellungen, wie die Qualit\u00e4t der Arbeiten \u2013 und vielleicht auch deren Bewertung \u2013 noch besser werden kann? <\/h5>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54ea97a elementor-widget elementor-widget-text-editor\" data-id=\"54ea97a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Christoph Bohlender:<\/strong> Ich war dieses Jahr erstmals Teil der neuen Design-Jury und habe erlebt, was passiert, wenn man eine kleine, hochkonzentrierte Gruppe von Kreativen zusammenbringt. Da sitzen Menschen, die sich bis ins Detail mit Ideen, Gestaltung und Kampagnen auseinandersetzen. Sie gehen jede Arbeit durch wie unter einem Mikroskop: inhaltlich und handwerklich. Sie finden die Schwachstellen, erkennen, was wirklich exzellent ist \u2013 fair, kritisch, wertsch\u00e4tzend. Diese reine kreative Urteilskraft schafft nochmal eine andere Tiefe. Genau diese Tiefe, diese akribische Suche nach Qualit\u00e4t, das w\u00fcrde ich gern noch mehr f\u00f6rdern.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85cd62b elementor-widget elementor-widget-heading\" data-id=\"85cd62b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Was bedeutet euer Agentur-Ansatz: \u201eErst verstehen, dann gestalten\u201d in einer Welt, die immer schneller, hektischer und lauter wird? <\/h5>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b1b790 elementor-widget elementor-widget-text-editor\" data-id=\"1b1b790\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Christoph Bohlender:<\/strong> \u201eErst verstehen\u201c ist eine Haltung, die schon immer die Basis guter Kommunikation war. Wer die richtigen Fragen stellt, beweist Gr\u00f6\u00dfe und vor allem Offenheit. Das gilt im Umgang mit K\u00fcnstlicher Intelligenz genauso wie im menschlichen Miteinander: Das Ergebnis wird nur dann brillant, wenn du tief genug fragst. Wenn du nicht tief genug gr\u00e4bst, bekommst du keine Antwort auf Fragen, die Menschen wirklich bewegen. Was das f\u00fcr unsere Arbeiten bedeutet? Wir suchen den Kern dessen, was Patienten oder \u00c4rztinnen und \u00c4rzte wirklich umtreibt. In einer Zeit, in der alle \u00fcberladen sind und sich nach Ruhe sehnen, filtern wir aus dieser Reiz\u00fcberflutung genau die eine Botschaft heraus, die ber\u00fchrt. \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5273f76 elementor-widget elementor-widget-heading\" data-id=\"5273f76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Was sollte man \u00fcber dich als neues \u201aGesicht\u2018 des COMPRIX unbedingt wissen, das nicht im offiziellen Profil steht? <\/h5>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ef0970 elementor-widget elementor-widget-text-editor\" data-id=\"3ef0970\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Christoph Bohlender:<\/strong> (lacht) Ich bin eigentlich ein bescheidener Mensch. Und ich glaube einfach nicht, dass man \u201ewichtig\u201c sein muss, um etwas zu bewegen. Ich mache Musik, habe Familie, lebe mein Leben \u2013 ich bin nicht wichtiger als die Arbeit, die wir machen. Aber wenn ich mir etwas w\u00fcnschen darf, dann, dass wir alle \u201eber\u00fchrbar\u201c bleiben. In der Healthcare-Kommunikation besch\u00e4ftigen wir uns oft mit sehr schweren Themen. Beim Bundesverband Kinderhospiz etwa \u2013 das geht mir pers\u00f6nlich sehr nahe, man m\u00f6chte manchmal am liebsten wegschauen.<\/p><p>Genau das nicht zu tun, geh\u00f6rt f\u00fcr mich zu unserer professionellen und menschlichen Verantwortung. Authentizit\u00e4t entsteht dort, wo wir bereit sind, uns auf die Geschichten der Menschen einzulassen \u2013 mit all ihrem Schmerz, ihrer Hoffnung und ihrer W\u00fcrde. Wer mit offenem Herzen durch die Welt l\u00e4uft, findet Antworten, die Menschen wirklich erreichen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-02fc611 elementor-widget elementor-widget-heading\" data-id=\"02fc611\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Wenn du eine Nacht lang an der Bar sitzen k\u00f6nntest \u2013 mit wem w\u00fcrdest du \u00fcber Ideen philosophieren? <\/h5>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b75bb9 elementor-widget elementor-widget-text-editor\" data-id=\"0b75bb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Christoph Bohlender:<\/strong> Ich brauche keine gro\u00dfen Legenden. Ich rede wahnsinnig gern mit meinen Kolleginnen und Kollegen. Es ist befl\u00fcgelnd, sich mit Menschen auszutauschen, die f\u00fcr ihre Arbeit brennen und die sich von guten Kampagnen inspirieren lassen \u2013 sei es in Cannes oder bei anderen Awards.<\/p><p>Es sind die Menschen, die diese Neugier behalten haben: die F\u00e4higkeit, sich begeistern zu lassen, sich selbst in Frage zu stellen, offen zu bleiben. Dieser Austausch \u00f6ffnet Horizonte. Und am Ende ist es genau diese Form von Gespr\u00e4ch, die uns menschlich und ber\u00fchrbar h\u00e4lt \u2013 und die Grundlage f\u00fcr Kommunikation schafft, die mehr ist als \u201eWerbung\u201c.<\/p><p>Unsere Arbeitswelt ist immer auch ein Spiegel unseres eigenen Seins. Was uns begegnet, resoniert mit dem, was in uns ist. Wenn wir bereit sind, diese Resonanz zuzulassen, entstehen Momente, die wir nicht planen k\u00f6nnen: Begegnungen, Ideen, Kampagnen, die wirklich etwas ver\u00e4ndern. Und genau daf\u00fcr ist der COMPRIX \u2013 im besten Sinne \u2013 eine B\u00fchne: f\u00fcr Arbeiten, die zeigen, dass Healthcare-Kommunikation um alles geht, was uns als Menschen ausmacht.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u201eBer\u00fchrbar bleiben\u201c Christoph Bohlender (MENSCH Kreativagentur) \u00fcber Healthcare-Kommunikation und gute Juryarbeit beim COMPRIX COMPRIX: Christoph, du bist neues Mitglied im COMPRIX-Beirat. Was treibt dich an, dich einzubringen? Christoph Bohlender: Der COMPRIX ist f\u00fcr mich das wichtigste Vehikel f\u00fcr kreative Healthcare-Kommunikation in Deutschland. Er kann eine B\u00fchne sein, die \u00fcber die Branche hinaus Wirkung entfaltet \u2013 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-882","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/award-stories.comprix.com\/club-der-fantasie\/wp-json\/wp\/v2\/pages\/882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/award-stories.comprix.com\/club-der-fantasie\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/award-stories.comprix.com\/club-der-fantasie\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/award-stories.comprix.com\/club-der-fantasie\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/award-stories.comprix.com\/club-der-fantasie\/wp-json\/wp\/v2\/comments?post=882"}],"version-history":[{"count":7,"href":"https:\/\/award-stories.comprix.com\/club-der-fantasie\/wp-json\/wp\/v2\/pages\/882\/revisions"}],"predecessor-version":[{"id":895,"href":"https:\/\/award-stories.comprix.com\/club-der-fantasie\/wp-json\/wp\/v2\/pages\/882\/revisions\/895"}],"wp:attachment":[{"href":"https:\/\/award-stories.comprix.com\/club-der-fantasie\/wp-json\/wp\/v2\/media?parent=882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}